{"id":3174,"date":"2018-10-26T09:39:47","date_gmt":"2018-10-26T16:39:47","guid":{"rendered":"http:\/\/linuspauling.preview.srv1.abidesites.com\/academics\/dual-immersion\/"},"modified":"2018-12-19T15:55:54","modified_gmt":"2018-12-19T23:55:54","slug":"dual-immersion","status":"publish","type":"page","link":"https:\/\/corvallisjuniorhigh.csd509j.net\/es\/academics\/dual-immersion\/","title":{"rendered":"Doble Inmersi\u00f3n"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":3163,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3174","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/corvallisjuniorhigh.csd509j.net\/es\/wp-json\/wp\/v2\/pages\/3174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corvallisjuniorhigh.csd509j.net\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/corvallisjuniorhigh.csd509j.net\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/corvallisjuniorhigh.csd509j.net\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/corvallisjuniorhigh.csd509j.net\/es\/wp-json\/wp\/v2\/comments?post=3174"}],"version-history":[{"count":0,"href":"https:\/\/corvallisjuniorhigh.csd509j.net\/es\/wp-json\/wp\/v2\/pages\/3174\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/corvallisjuniorhigh.csd509j.net\/es\/wp-json\/wp\/v2\/pages\/3163"}],"wp:attachment":[{"href":"https:\/\/corvallisjuniorhigh.csd509j.net\/es\/wp-json\/wp\/v2\/media?parent=3174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}